{"id":17745,"date":"2025-01-01T02:30:17","date_gmt":"2024-12-31T23:30:17","guid":{"rendered":"https:\/\/musovuno.com\/hi\/?p=17745"},"modified":"2025-01-01T02:30:17","modified_gmt":"2024-12-31T23:30:17","slug":"xcho-mot-ballada","status":"publish","type":"post","link":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/","title":{"rendered":"Xcho  \u041c\u041e\u0422 &#8211; \u0411\u0430\u043b\u043b\u0430\u0434\u0430"},"content":{"rendered":"<p>Xcho  \u041c\u041e\u0422 &#8211; \u0411\u0430\u043b\u043b\u0430\u0434\u0430<br \/>\n<iframe loading=\"lazy\" title=\"Xcho &amp; \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 (Official Audio)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/dyaa9FCvC6Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Xcho \u041c\u041e\u0422 &#8211; \u0411\u0430\u043b\u043b\u0430\u0434\u0430<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_trash_the_other_posts":false,"footnotes":""},"categories":[2514,2546],"tags":[],"class_list":["post-17745","post","type-post","status-publish","format-standard","hentry","category-pop","category-roosee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u09403 \u0938\u0902\u0917\u0940\u0924, \u0917\u0940\u0924 \u0914\u0930 \u0935\u0940\u0921\u093f\u092f\u094b \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0915\u0930\u0947\u0902<\/title>\n<meta name=\"description\" content=\"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u0940 3 \u092e\u0941\u092b\u094d\u0924 \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0911\u0928\u0932\u093e\u0907\u0928, \u0938\u0902\u0917\u0940\u0924 \u0917\u0940\u0924 \u0914\u0930 \u0917\u0940\u0924 \u0936\u092c\u094d\u0926, \u0935\u0940\u0921\u093f\u092f\u094b \u0938\u0902\u0917\u0940\u0924 \u0915\u094d\u0932\u093f\u092a \u0926\u0947\u0916\u0947\u0902.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/\" \/>\n<meta property=\"og:locale\" content=\"hi_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u09403 \u0938\u0902\u0917\u0940\u0924, \u0917\u0940\u0924 \u0914\u0930 \u0935\u0940\u0921\u093f\u092f\u094b \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0915\u0930\u0947\u0902\" \/>\n<meta property=\"og:description\" content=\"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u0940 3 \u092e\u0941\u092b\u094d\u0924 \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0911\u0928\u0932\u093e\u0907\u0928, \u0938\u0902\u0917\u0940\u0924 \u0917\u0940\u0924 \u0914\u0930 \u0917\u0940\u0924 \u0936\u092c\u094d\u0926, \u0935\u0940\u0921\u093f\u092f\u094b \u0938\u0902\u0917\u0940\u0924 \u0915\u094d\u0932\u093f\u092a \u0926\u0947\u0916\u0947\u0902.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/\" \/>\n<meta property=\"og:site_name\" content=\"Musovuno HI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musovuno\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-31T23:30:17+00:00\" \/>\n<meta name=\"author\" content=\"ingrida\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musovuno\" \/>\n<meta name=\"twitter:site\" content=\"@musovuno\" \/>\n<meta name=\"twitter:label1\" content=\"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924\" \/>\n\t<meta name=\"twitter:data1\" content=\"ingrida\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/xcho-mot-ballada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/xcho-mot-ballada\\\/\"},\"author\":{\"name\":\"ingrida\",\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/#\\\/schema\\\/person\\\/d845fed1d30c5768c9f772f343803a8c\"},\"headline\":\"Xcho \u041c\u041e\u0422 &#8211; \u0411\u0430\u043b\u043b\u0430\u0434\u0430\",\"datePublished\":\"2024-12-31T23:30:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/xcho-mot-ballada\\\/\"},\"wordCount\":18,\"publisher\":{\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/#organization\"},\"articleSection\":[\"\u092a\u0949\u092a \u0938\u0902\u0917\u0940\u0924\",\"\u0930\u0942\u0938\u0940 \u0938\u0902\u0917\u0940\u0924\"],\"inLanguage\":\"hi-IN\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/xcho-mot-ballada\\\/\",\"url\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/xcho-mot-ballada\\\/\",\"name\":\"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u09403 \u0938\u0902\u0917\u0940\u0924, \u0917\u0940\u0924 \u0914\u0930 \u0935\u0940\u0921\u093f\u092f\u094b \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0915\u0930\u0947\u0902\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/#website\"},\"datePublished\":\"2024-12-31T23:30:17+00:00\",\"description\":\"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u0940 3 \u092e\u0941\u092b\u094d\u0924 \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0911\u0928\u0932\u093e\u0907\u0928, \u0938\u0902\u0917\u0940\u0924 \u0917\u0940\u0924 \u0914\u0930 \u0917\u0940\u0924 \u0936\u092c\u094d\u0926, \u0935\u0940\u0921\u093f\u092f\u094b \u0938\u0902\u0917\u0940\u0924 \u0915\u094d\u0932\u093f\u092a \u0926\u0947\u0916\u0947\u0902.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/xcho-mot-ballada\\\/#breadcrumb\"},\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/musovuno.com\\\/hi\\\/xcho-mot-ballada\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/xcho-mot-ballada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0938\u0902\u0917\u0940\u0924\",\"item\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/sangeet\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0938\u0902\u0917\u0940\u0924 \u0936\u0948\u0932\u093f\u092f\u093e\u0901\",\"item\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/sangeet\\\/shailiyaan\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u092a\u0949\u092a \u0938\u0902\u0917\u0940\u0924\",\"item\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/sangeet\\\/shailiyaan\\\/pop\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Xcho \u041c\u041e\u0422 &#8211; \u0411\u0430\u043b\u043b\u0430\u0434\u0430\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/#website\",\"url\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/\",\"name\":\"Musovuno\",\"description\":\"\u0938\u0902\u0917\u0940\u0924, \u0917\u0940\u0924 \u0914\u0930 \u0938\u0902\u0917\u0940\u0924 \u0935\u0940\u0921\u093f\u092f\u094b\",\"publisher\":{\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/#organization\"},\"alternateName\":\"Musovuno\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hi-IN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/#organization\",\"name\":\"Musovuno\",\"alternateName\":\"Musovuno\",\"url\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/09\\\/cropped-favicon-2.png\",\"contentUrl\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/09\\\/cropped-favicon-2.png\",\"width\":512,\"height\":512,\"caption\":\"Musovuno\"},\"image\":{\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musovuno\",\"https:\\\/\\\/x.com\\\/musovuno\",\"https:\\\/\\\/www.instagram.com\\\/musovuno\",\"https:\\\/\\\/www.youtube.com\\\/musovuno\",\"https:\\\/\\\/pinterest.com\\\/musovuno\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/#\\\/schema\\\/person\\\/d845fed1d30c5768c9f772f343803a8c\",\"name\":\"ingrida\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/wp-content\\\/litespeed\\\/avatar\\\/25\\\/6a2994bcd4484eaa467a7755a3f81848.jpg?ver=1788294678\",\"url\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/wp-content\\\/litespeed\\\/avatar\\\/25\\\/6a2994bcd4484eaa467a7755a3f81848.jpg?ver=1788294678\",\"contentUrl\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/wp-content\\\/litespeed\\\/avatar\\\/25\\\/6a2994bcd4484eaa467a7755a3f81848.jpg?ver=1788294678\",\"caption\":\"ingrida\"},\"url\":\"https:\\\/\\\/musovuno.com\\\/hi\\\/author\\\/ingrida\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u09403 \u0938\u0902\u0917\u0940\u0924, \u0917\u0940\u0924 \u0914\u0930 \u0935\u0940\u0921\u093f\u092f\u094b \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0915\u0930\u0947\u0902","description":"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u0940 3 \u092e\u0941\u092b\u094d\u0924 \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0911\u0928\u0932\u093e\u0907\u0928, \u0938\u0902\u0917\u0940\u0924 \u0917\u0940\u0924 \u0914\u0930 \u0917\u0940\u0924 \u0936\u092c\u094d\u0926, \u0935\u0940\u0921\u093f\u092f\u094b \u0938\u0902\u0917\u0940\u0924 \u0915\u094d\u0932\u093f\u092a \u0926\u0947\u0916\u0947\u0902.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/","og_locale":"hi_IN","og_type":"article","og_title":"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u09403 \u0938\u0902\u0917\u0940\u0924, \u0917\u0940\u0924 \u0914\u0930 \u0935\u0940\u0921\u093f\u092f\u094b \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0915\u0930\u0947\u0902","og_description":"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u0940 3 \u092e\u0941\u092b\u094d\u0924 \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0911\u0928\u0932\u093e\u0907\u0928, \u0938\u0902\u0917\u0940\u0924 \u0917\u0940\u0924 \u0914\u0930 \u0917\u0940\u0924 \u0936\u092c\u094d\u0926, \u0935\u0940\u0921\u093f\u092f\u094b \u0938\u0902\u0917\u0940\u0924 \u0915\u094d\u0932\u093f\u092a \u0926\u0947\u0916\u0947\u0902.","og_url":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/","og_site_name":"Musovuno HI","article_publisher":"https:\/\/www.facebook.com\/musovuno","article_published_time":"2024-12-31T23:30:17+00:00","author":"ingrida","twitter_card":"summary_large_image","twitter_creator":"@musovuno","twitter_site":"@musovuno","twitter_misc":{"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924":"ingrida"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/#article","isPartOf":{"@id":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/"},"author":{"name":"ingrida","@id":"https:\/\/musovuno.com\/hi\/#\/schema\/person\/d845fed1d30c5768c9f772f343803a8c"},"headline":"Xcho \u041c\u041e\u0422 &#8211; \u0411\u0430\u043b\u043b\u0430\u0434\u0430","datePublished":"2024-12-31T23:30:17+00:00","mainEntityOfPage":{"@id":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/"},"wordCount":18,"publisher":{"@id":"https:\/\/musovuno.com\/hi\/#organization"},"articleSection":["\u092a\u0949\u092a \u0938\u0902\u0917\u0940\u0924","\u0930\u0942\u0938\u0940 \u0938\u0902\u0917\u0940\u0924"],"inLanguage":"hi-IN"},{"@type":"WebPage","@id":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/","url":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/","name":"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u09403 \u0938\u0902\u0917\u0940\u0924, \u0917\u0940\u0924 \u0914\u0930 \u0935\u0940\u0921\u093f\u092f\u094b \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0915\u0930\u0947\u0902","isPartOf":{"@id":"https:\/\/musovuno.com\/hi\/#website"},"datePublished":"2024-12-31T23:30:17+00:00","description":"Xcho \u041c\u041e\u0422 - \u0411\u0430\u043b\u043b\u0430\u0434\u0430 \u090f\u092e\u092a\u0940 3 \u092e\u0941\u092b\u094d\u0924 \u0921\u093e\u0909\u0928\u0932\u094b\u0921 \u0911\u0928\u0932\u093e\u0907\u0928, \u0938\u0902\u0917\u0940\u0924 \u0917\u0940\u0924 \u0914\u0930 \u0917\u0940\u0924 \u0936\u092c\u094d\u0926, \u0935\u0940\u0921\u093f\u092f\u094b \u0938\u0902\u0917\u0940\u0924 \u0915\u094d\u0932\u093f\u092a \u0926\u0947\u0916\u0947\u0902.","breadcrumb":{"@id":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/#breadcrumb"},"inLanguage":"hi-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/musovuno.com\/hi\/xcho-mot-ballada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/musovuno.com\/hi\/"},{"@type":"ListItem","position":2,"name":"\u0938\u0902\u0917\u0940\u0924","item":"https:\/\/musovuno.com\/hi\/sangeet\/"},{"@type":"ListItem","position":3,"name":"\u0938\u0902\u0917\u0940\u0924 \u0936\u0948\u0932\u093f\u092f\u093e\u0901","item":"https:\/\/musovuno.com\/hi\/sangeet\/shailiyaan\/"},{"@type":"ListItem","position":4,"name":"\u092a\u0949\u092a \u0938\u0902\u0917\u0940\u0924","item":"https:\/\/musovuno.com\/hi\/sangeet\/shailiyaan\/pop\/"},{"@type":"ListItem","position":5,"name":"Xcho \u041c\u041e\u0422 &#8211; \u0411\u0430\u043b\u043b\u0430\u0434\u0430"}]},{"@type":"WebSite","@id":"https:\/\/musovuno.com\/hi\/#website","url":"https:\/\/musovuno.com\/hi\/","name":"Musovuno","description":"\u0938\u0902\u0917\u0940\u0924, \u0917\u0940\u0924 \u0914\u0930 \u0938\u0902\u0917\u0940\u0924 \u0935\u0940\u0921\u093f\u092f\u094b","publisher":{"@id":"https:\/\/musovuno.com\/hi\/#organization"},"alternateName":"Musovuno","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musovuno.com\/hi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hi-IN"},{"@type":"Organization","@id":"https:\/\/musovuno.com\/hi\/#organization","name":"Musovuno","alternateName":"Musovuno","url":"https:\/\/musovuno.com\/hi\/","logo":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/musovuno.com\/hi\/#\/schema\/logo\/image\/","url":"https:\/\/musovuno.com\/hi\/wp-content\/uploads\/sites\/25\/2024\/09\/cropped-favicon-2.png","contentUrl":"https:\/\/musovuno.com\/hi\/wp-content\/uploads\/sites\/25\/2024\/09\/cropped-favicon-2.png","width":512,"height":512,"caption":"Musovuno"},"image":{"@id":"https:\/\/musovuno.com\/hi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musovuno","https:\/\/x.com\/musovuno","https:\/\/www.instagram.com\/musovuno","https:\/\/www.youtube.com\/musovuno","https:\/\/pinterest.com\/musovuno"]},{"@type":"Person","@id":"https:\/\/musovuno.com\/hi\/#\/schema\/person\/d845fed1d30c5768c9f772f343803a8c","name":"ingrida","image":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/musovuno.com\/hi\/wp-content\/litespeed\/avatar\/25\/6a2994bcd4484eaa467a7755a3f81848.jpg?ver=1788294678","url":"https:\/\/musovuno.com\/hi\/wp-content\/litespeed\/avatar\/25\/6a2994bcd4484eaa467a7755a3f81848.jpg?ver=1788294678","contentUrl":"https:\/\/musovuno.com\/hi\/wp-content\/litespeed\/avatar\/25\/6a2994bcd4484eaa467a7755a3f81848.jpg?ver=1788294678","caption":"ingrida"},"url":"https:\/\/musovuno.com\/hi\/author\/ingrida\/"}]}},"_links":{"self":[{"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/posts\/17745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/comments?post=17745"}],"version-history":[{"count":1,"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/posts\/17745\/revisions"}],"predecessor-version":[{"id":17856,"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/posts\/17745\/revisions\/17856"}],"wp:attachment":[{"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/media?parent=17745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/categories?post=17745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musovuno.com\/hi\/wp-json\/wp\/v2\/tags?post=17745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}